{"id":706,"date":"2010-06-30T13:11:52","date_gmt":"2010-06-30T12:11:52","guid":{"rendered":"http:\/\/www.thomaskeller.biz\/blog\/?p=706"},"modified":"2010-06-30T13:24:41","modified_gmt":"2010-06-30T12:24:41","slug":"land-des-stillstands","status":"publish","type":"post","link":"https:\/\/www.thomaskeller.biz\/blog\/2010\/06\/30\/land-des-stillstands\/","title":{"rendered":"Land des Stillstands"},"content":{"rendered":"<p>Die Spatzen twittern, \u00e4h, pfeifen es von den D\u00e4chern, Wulff ist wohl durch. Finde ich sehr sch\u00f6n, wurde doch somit die letzte, kantige Personalie in Berlin (K\u00f6hler) durch einen weiteren CDU\/CSU-getreuen Vasallen ersetzt. Was ich pers\u00f6nlich von Herrn Wulff erwarte? Nun, viel mehr als die j\u00e4hrliche Neujahrsansprache wohl sicherlich nicht&#8230;<\/p>\n<p><b>[Update: <\/b>Wulff fehlten doch noch 32 Stimmen, Gauck hatte 599. Wurde wohl doch falsch gezwitschert, wenn nun die Linke geschlossen f\u00fcr Gauck votieren w\u00fcrde&#8230;, ja, das w\u00e4rs.<b>]<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Spatzen twittern, \u00e4h, pfeifen es von den D\u00e4chern, Wulff ist wohl durch. Finde ich sehr sch\u00f6n, wurde doch somit die letzte, kantige Personalie in Berlin (K\u00f6hler) durch einen weiteren CDU\/CSU-getreuen Vasallen ersetzt. Was ich pers\u00f6nlich von Herrn Wulff erwarte? Nun, viel mehr als die j\u00e4hrliche Neujahrsansprache wohl sicherlich nicht&#8230; [Update: Wulff fehlten doch noch &hellip; <a href=\"https:\/\/www.thomaskeller.biz\/blog\/2010\/06\/30\/land-des-stillstands\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Land des Stillstands<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-706","post","type-post","status-publish","format-standard","hentry","category-german"],"_links":{"self":[{"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/posts\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/comments?post=706"}],"version-history":[{"count":3,"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/posts\/706\/revisions"}],"predecessor-version":[{"id":708,"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/posts\/706\/revisions\/708"}],"wp:attachment":[{"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/media?parent=706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/categories?post=706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thomaskeller.biz\/blog\/wp-json\/wp\/v2\/tags?post=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}